{"id":4302,"date":"2015-10-01T17:06:11","date_gmt":"2015-10-02T00:06:11","guid":{"rendered":"http:\/\/www.inmexico.com\/?page_id=4302"},"modified":"2015-11-30T13:04:11","modified_gmt":"2015-11-30T20:04:11","slug":"normas-reglamentos-top-of-mex","status":"publish","type":"page","link":"http:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/","title":{"rendered":"Normas &#038; Reglamentos \u2013 Top of Mex"},"content":{"rendered":"<h1 style=\"text-align: center;\">#TOPOFMEX<\/h1>\n<div class=\"panel panel-default\">\n<div id=\"collapseSix\" class=\"\">\n<div class=\"panel-body\">\n<h4>CONCURSO TOP OF MEX<\/h4>\n<p>\u00bfQui\u00e9nes son sus personajes favoritos de Los Cabos? \u00bfCu\u00e1l es su lugar preferido para ir a comer? \u00bfCu\u00e1les son los lugares que frecuentan los locales? \u00a1Queremos escucharlo!<\/p>\n<p>Los ganadores ser\u00e1n mencionados en <em>InMexico: Top of Mex<\/em>, una edici\u00f3n especial de la revista <em>InMexico<\/em> que se publica una vez al a\u00f1o. Adicionalmente, los ganadores obtendr\u00e1n el derecho a utilizar el logotipo de \u201cGanador Top of Mex-2016\u201d de <em>InMexico <\/em>en todos sus materiales promocionales, en su p\u00e1gina Web y en las instalaciones de su negocio por tiempo indefinido.<\/p>\n<p>Para nominar a un negocio, persona o cosa, por favor env\u00ede un correo electr\u00f3nico a topofmex@inmexico.com antes del 30 de septiembre de 2015.<\/p>\n<p>El concurso se llevar\u00e1 a cabo del 1ero de octubre al 30 de noviembre de 2015.<\/p>\n<p>Para ver todas las Normas &amp; Reglamentos, presione aqu\u00ed.<\/p>\n<h4>NORMAS &amp; REGLAMENTOS \u2013 TOP OF MEX (2015-2016)<\/h4>\n<p>No es necesario efectuar ninguna compra para participar en este concurso. Adem\u00e1s de los requisitos que se establecen a continuaci\u00f3n, el concurso Top of Mex de <em>InMexico<\/em>, o \u201cConcurso\u201d, est\u00e1 abierto a todos los negocios con excepci\u00f3n de los directores, oficiales, agentes y empleados de Media That Deelivers y sus respectivas entidades afiliadas y asociadas, as\u00ed como a sus respectivos familiares directos que vivan en el mismo domicilio.<\/p>\n<p>Al nominar o votar por un negocio o individuo, los participantes aceptan los t\u00e9rminos y condiciones de estas Normas y aceptan estar obligados por ellos. Este concurso est\u00e1 sujeto a todas las leyes y regulaciones aplicables a nivel federal, estatal y local. Este concurso es nulo donde la ley lo proh\u00edba. La Revista <em>InMexico<\/em> y Media That Deelivers, Inc. se reservan el derecho a interpretar los votos a su criterio, sacar o suspender a cualquier participante, cambiar cualquier funci\u00f3n o caracter\u00edstica de la p\u00e1gina web y modificar los t\u00e9rminos y condiciones en cualquier momento y sin previo aviso.<\/p>\n<h4>TOP OF MEX &#8211; NOMINACIONES<\/h4>\n<p>Si usted desea nominar un negocio para que haga parte del concurso, env\u00ede un correo electr\u00f3nico a topofmex@inmexico.com\u00a0antes del <strong>1ero de septiembre de 2015<\/strong>.<\/p>\n<p><em>Para ser considerada, cada nominaci\u00f3n que se env\u00ede debe incluir lo siguiente:<\/em><\/p>\n<p>1) Nombre y descripci\u00f3n del negocio<\/p>\n<p>2) Datos de contacto, incluyendo el nombre del due\u00f1o del negocio, agencia, o representante de relaciones p\u00fablicas, direcci\u00f3n, URL, numero de tel\u00e9fono, direcci\u00f3n de correo electr\u00f3nico y cuentas en redes sociales.<\/p>\n<p>3) Las categor\u00edas a las que usted piense que pertenece el negocio (Ejemplos: <strong>Mejor Resort de Lujo, Mejor Entrenador F\u00edsico, Mejor Estilista,<\/strong> etc.). Solo una nominaci\u00f3n por persona por negocio es necesaria. Todas las nominaciones que se reciban dentro del plazo ser\u00e1n consideradas. Las probabilidades de ganar dependen del n\u00famero de nominaciones elegibles que sean recibidas.<\/p>\n<p>Al ingresar su nominaci\u00f3n, la informaci\u00f3n de \u00e9sta se convierte en propiedad de Arizona Foothills Magazine y Media That Deelivers.\u00a0Todas las nominaciones se deben recibir antes del plazo de nominaci\u00f3n.<\/p>\n<p>El plazo de nominaci\u00f3n para el concurso Top of Mex 2016 finaliza a las 11:59:59 a.m. (GMT) el 1ero de septiembre de 2015.<\/p>\n<h4>TOP OF MEX &#8211; FINALISTAS<\/h4>\n<p>Todos los nominados para el concurso ser\u00e1n evaluados inicialmente por los editores de <em>InMexico<\/em> y por grupos focales locales para determinar a los finalistas de cada categor\u00eda. La selecci\u00f3n de los finalistas ser\u00e1 a discreci\u00f3n de nuestros editores, ya que los seleccionados tendr\u00e1n que cumplir con los est\u00e1ndares de integridad previstos por <em>InMexico<\/em>. Todos los nominados ser\u00e1n notificados por correo electr\u00f3nico, Twitter o tel\u00e9fono. Cualquier nominado puede retirarse del concurso en cualquier momento.<\/p>\n<h4>TOP OF MEX \u2013 VOTACI\u00d3N FINAL<\/h4>\n<p><em>InMexico<\/em> y el panel seleccionar\u00e1 a los nominados de Top of Mex cuyos negocios o nombres ser\u00e1n sometidos a votaci\u00f3n en nuestra p\u00e1gina web. La votaci\u00f3n se llevar\u00e1 a cabo a partir de las 12:00:01 p.m. (GMT) el 1ero de octubre de 2015 y finalizar\u00e1 a las 11:59:59 p.m. (MST) el 30 de noviembre de 2015.<\/p>\n<p>Negocios, individuos y clientes de los negocios pueden votar una vez al d\u00eda por cada categor\u00eda dentro del plazo de dos meses mencionado. Cada voto cuenta cuando un usuario hace clic en el bot\u00f3n \u201cVotar\u201d asociado con cada uno de los nominados. El ganador de cada categor\u00eda es el negocio o individuo con mayor cantidad de votos dentro de su categor\u00eda cuando el reloj marque las 12:00:00 PM el 1 de diciembre de 2015.<\/p>\n<h4>TOP OF MEX &#8211; DESCALIFICACIONES<\/h4>\n<p>El uso de bots y sistemas mec\u00e1nicos de votaci\u00f3n son inaceptables. Si nuestro servidor detecta este tipo de votaci\u00f3n falsa, la direcci\u00f3n IP asociada no podr\u00e1 utilizarse m\u00e1s para ingresar votos. <em>InMexico<\/em> y Media That Deelivers, Inc. se reservan el derecho de descalificar a cualquier negocio o individuo de quien sospechen su participaci\u00f3n en este tipo de actividad, o cualquier otro tipo de actividad relacionada con la obtenci\u00f3n deshonesta de votos.<\/p>\n<h4>TOP OF MEX \u2013 GANADORES<\/h4>\n<p>En cada categor\u00eda deber\u00e1 haber un negocio o individuo ganador. Los ganadores de cada categor\u00eda ser\u00e1n notificados en diciembre del 2015 y recibir\u00e1n lo siguiente:<\/p>\n<p>1) Una menci\u00f3n en la edici\u00f3n \u201c<em>InMexico: Top of Mex<\/em>\u201d del 2016<\/p>\n<p>El tama\u00f1o de la menci\u00f3n a\u00fan no se ha determinado.<\/p>\n<p>No podemos garantizar: el n\u00famero de palabras, la inclusi\u00f3n de fotos, ni los detalles del escrito.<\/p>\n<p>No todos los negocios\/individuos recibir\u00e1n el mismo tama\u00f1o de menci\u00f3n<\/p>\n<p>Los editores se reservan el derecho de incluir a distintos negocios\/individuos que no formaron parte del concurso<\/p>\n<p>Los ganadores del concurso no tendr\u00e1n la oportunidad de ver o aprobar la menci\u00f3n antes de su publicaci\u00f3n<\/p>\n<p>No es necesario que los ganadores contacten a INMEXICO o a Media That Deelivers, Inc. Nuestros editores se encargar\u00e1n de contactar a cada uno de los ganadores conforme sea necesario.<\/p>\n<p>2) <strong>El derecho a utilizar el logotipo de \u201cGanador Top of Mex-2016\u201d de <em>InMexico<\/em> en todos sus materiales promocionales, en su p\u00e1gina Web y en las instalaciones de su negocio por tiempo indefinido.<\/strong><\/p>\n<p>Los logotipos se enviar\u00e1n a los ganadores por medio de correo electr\u00f3nico en diciembre de 2015.<\/p>\n<p>Oportunidades de promoci\u00f3n en el pr\u00f3ximo a\u00f1o exclusivas para los ganadores<\/p>\n<p>Estas oportunidades pueden incluir eventos especiales y otras iniciativas de marketing.<\/p>\n<p>Estos eventos est\u00e1n por determinarse y no est\u00e1n garantizados.<\/p>\n<h4>PREMIOS ADICIONALES<\/h4>\n<p>Dependiendo del nivel de participaci\u00f3n de los patrocinadores de \u201cTop of Mex\u201d, es posible que puedan otorg\u00e1rsele premios adicionales a los ganadores y finalistas del concurso.<\/p>\n<h4>TERMINOS &amp; CONDICIONES DE LOS PREMIOS<\/h4>\n<p>Todos los premios y beneficios aqu\u00ed mencionados se deben aceptar como se ofrecen y no son intercambiables, transferibles, redimibles por dinero en efectivo o reventa. No se permiten premios alternativos, dinero en efectivo, ni ninguna otra sustituci\u00f3n del premio o de parte(s) del premio excepto que el patrocinador lo decida a su discreci\u00f3n. Los premios no se pueden reembolsar, transferir, volver a emitir, revalidar o combinar con ninguna otra oferta. Los premios deben de ser reclamados en el plazo de un mes de la fecha en que se otorguen. No se proporcionar\u00e1n vales para un uso posterior. En el caso de que los premios, o cualquiera de sus componentes, no se puedan otorgar como se estipul\u00f3 anteriormente, los patrocinadores se reservan el derecho a otorgar un premio sustituto de igual o mayor valor sin adeudo y sin incurrir en responsabilidad alguna. En caso de que cualquiera de los ganadores no utilice cualquier porci\u00f3n de los premios otorgados, no habr\u00e1 reembolso, extensi\u00f3n, transferencia o sustituci\u00f3n de los mismos, ni se proporcionar\u00e1 ning\u00fan tipo de compensaci\u00f3n.<\/p>\n<p>Todos los participantes del Concurso deben cumplir estas Normas. Al participar en este Concurso, todos los participantes irrevocablemente otorgan a <em>InMexico<\/em> el derecho a incluir su nombre e informaci\u00f3n en cualquiera de las listas de distribuci\u00f3n de <em>InMexico<\/em>, as\u00ed como el derecho a utilizar su nombre en cualquier publicidad realizada por <em>InMexic<\/em>o. Asimismo, los participantes aceptan conceder una licencia y derechos irrevocables y no exclusivos, de cualquier forma y en todo el mundo, de utilizar y reproducir su fotograf\u00eda, voz, nombre y\/o su semejante, en parte o en su totalidad, en o en relaci\u00f3n a la publicidad, exposici\u00f3n, marketing, promoci\u00f3n y explotaci\u00f3n de la empresa <em>InMexico<\/em>. Los individuos que no deseen que su informaci\u00f3n personal sea utilizada para dichos prop\u00f3sitos de promoci\u00f3n y publicidad (de lo contrario no relacionados al Concurso) deber\u00e1n indicarlo por escrito a <em>InMexico<\/em> y hac\u00e9rnoslo llegar a la siguiente direcci\u00f3n: Media That Deelivers, 8132 N. 87th PL, Scottsdale, AZ 85258 ATTN: <em>InMexico<\/em>.<\/p>\n<p>En ning\u00fan caso, ni los Patrocinadores ni sus respectivas entidades afiliadas o asociadas, ser\u00e1n responsables de las cancelaciones y retrasos que ocurran debido a circunstancias que est\u00e9n razonablemente fuera de su control. Los participantes del Concurso asumen toda responsabilidad por lesiones causadas o supuestamente causadas por su participaci\u00f3n en este Concurso, o el uso y\/o mal uso de cualquier premio otorgado, incluyendo cualquier p\u00e9rdida, da\u00f1os, reclamaciones y acciones (o causas de acciones) de cualquier tipo en relaci\u00f3n a cualquier premio otorgado, incluyendo, sin limitaci\u00f3n, todos los riesgos y responsabilidades relacionados con los viajes. Sin limitar la generalidad de lo anterior, al hacer parte de este Concurso, todos los participantes exoneran y desligan para siempre a los Patrocinadores y a sus respectivas empresas matrices, afiliados, subsidiarios, agentes y asesores, as\u00ed como a sus empleados, funcionarios, directores, accionistas, agentes y representantes, de todos los da\u00f1os, derechos, reclamos y acciones de cualquier tipo que surjan en relaci\u00f3n al Concurso o que sean resultado de la aceptaci\u00f3n, posesi\u00f3n, y\/o uso o mal uso de cualquier premio otorgado en relaci\u00f3n al Concurso, incluyendo, sin limitaci\u00f3n, lesiones personales, muerte y\/o da\u00f1os a la propiedad, as\u00ed como reclamos basados en derechos de publicidad, difamaci\u00f3n o invasi\u00f3n de la privacidad. Los Patrocinadores y sus respectivas entidades afiliadas y asociadas no asumen responsabilidad alguna por la p\u00e9rdida, el robo, los da\u00f1os, la recepci\u00f3n tard\u00eda, el env\u00edo err\u00f3neo y\/o la ilegibilidad de los formularios de entrada de datos, ni por cualquier fallo en el funcionamiento, ya sea en l\u00ednea, t\u00e9cnico, computacional y\/o error humano, que pueda ocurrir en la administraci\u00f3n del Concurso. Si por cualquier motivo el Concurso no se puede llevar a cabo de la manera prevista debido a un virus inform\u00e1tico, un defecto inform\u00e1tico, una alteraci\u00f3n, una intervenci\u00f3n no autorizada, un fraude, fallas t\u00e9cnicas, o cualquier otra causa fuera del control de los Patrocinadores, o de sus respectivas entidades afiliadas y asociadas, o cualquier acci\u00f3n que interfiera con la administraci\u00f3n, seguridad, imparcialidad, integridad o conducta apropiada de este Concurso, los Patrocinadores se reservan el derecho, a su entera y absoluta discreci\u00f3n, de descalificar a un individuo y\/o cancelar, terminar, modificar o suspender el Concurso. Los Patrocinadores y sus respectivas entidades afiliadas y asociadas no ser\u00e1n responsables, bajo ninguna circunstancia, de ning\u00fan problema o falla t\u00e9cnica en relaci\u00f3n al Concurso, ni de cualquier error tipogr\u00e1fico o de impresi\u00f3n en cualquier material relacionado con el Concurso.<\/p>\n<p>Cualquier intento de cualquier persona no autorizada de interrumpir o alterar el Concurso ser\u00e1 considerado una violaci\u00f3n de las leyes penales y civiles. Los Patrocinadores y sus respectivas entidades afiliadas y asociadas se reservan el derecho de exigir compensaci\u00f3n por da\u00f1os o cualquier otro tipo de compensaci\u00f3n a dicha persona. En caso de que haya una controversia relacionada con votos ingresados por varios usuarios con la misma direcci\u00f3n de correo electr\u00f3nico, los votos se considerar\u00e1n ingresados por el titular autorizado de la cuenta de correo electr\u00f3nico que se ingres\u00f3 al votar. El titular autorizado de la cuenta es la persona natural a quien se le asigna la direcci\u00f3n de correo electr\u00f3nico por medio de un proveedor de acceso a internet, proveedor de servicios en l\u00ednea, u otra organizaci\u00f3n que sea responsable de asignar direcciones de correo electr\u00f3nico o el dominio asociado con la direcci\u00f3n de correo electr\u00f3nico ingresada. Es posible que a lo Ganadores del Concurso se le exija proporcionar una prueba (a <em>InMexico<\/em>) de que son los titulares autorizados de la cuenta de correo electr\u00f3nico asociada con las entradas ganadoras, o de lo contrario, deber\u00e1n renunciar a cualquier premio otorgado. Es exclusiva responsabilidad del concursante notificar a <em>InMexico<\/em>, por medio de un escrito enviado a la direcci\u00f3n mencionada anteriormente, de cualquier cambio en su direcci\u00f3n de correo electr\u00f3nico o n\u00famero de tel\u00e9fono. Todos los cambios deber\u00e1n ser recibidos antes del plazo del concurso. Todas las cifras monetarias que aqu\u00ed se expresan son en d\u00f3lares estadounidenses.<\/p>\n<p>Las Normas &amp; Reglamentos de este concurso pueden cambiar en cualquier momento. Todos los premios relacionados con este concurso no tienen ning\u00fan valor monetario y no son canjeables por dinero en efectivo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>#TOPOFMEX CONCURSO TOP OF MEX \u00bfQui\u00e9nes son sus personajes favoritos de Los Cabos? \u00bfCu\u00e1l es su lugar preferido para ir a comer? \u00bfCu\u00e1les son los lugares que frecuentan los&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-layout-full-width.php","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-4302","page","type-page","status-publish","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Normas &amp; Reglamentos \u2013 Top of Mex - InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Normas &amp; Reglamentos \u2013 Top of Mex - InMexico\" \/>\n<meta property=\"og:description\" content=\"#TOPOFMEX CONCURSO TOP OF MEX \u00bfQui\u00e9nes son sus personajes favoritos de Los Cabos? \u00bfCu\u00e1l es su lugar preferido para ir a comer? \u00bfCu\u00e1les son los lugares que frecuentan los...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-30T20:04:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/\",\"url\":\"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/\",\"name\":\"Normas & Reglamentos \u2013 Top of Mex - InMexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/#website\"},\"datePublished\":\"2015-10-02T00:06:11+00:00\",\"dateModified\":\"2015-11-30T20:04:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inmexico.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Normas &#038; Reglamentos \u2013 Top of Mex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inmexico.com\/#website\",\"url\":\"https:\/\/www.inmexico.com\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"publisher\":{\"@id\":\"https:\/\/www.inmexico.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inmexico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.inmexico.com\/#organization\",\"name\":\"InMexico\",\"alternateName\":\"InMexico\",\"url\":\"https:\/\/www.inmexico.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"contentUrl\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"width\":678,\"height\":208,\"caption\":\"InMexico\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/inmexicocom\",\"https:\/\/x.com\/inmexicocom\",\"https:\/\/www.instagram.com\/in.mexico\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Normas & Reglamentos \u2013 Top of Mex - InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/","og_locale":"es_MX","og_type":"article","og_title":"Normas & Reglamentos \u2013 Top of Mex - InMexico","og_description":"#TOPOFMEX CONCURSO TOP OF MEX \u00bfQui\u00e9nes son sus personajes favoritos de Los Cabos? \u00bfCu\u00e1l es su lugar preferido para ir a comer? \u00bfCu\u00e1les son los lugares que frecuentan los...","og_url":"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","article_modified_time":"2015-11-30T20:04:11+00:00","twitter_card":"summary_large_image","twitter_site":"@inmexicocom","twitter_misc":{"Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/","url":"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/","name":"Normas & Reglamentos \u2013 Top of Mex - InMexico","isPartOf":{"@id":"https:\/\/www.inmexico.com\/#website"},"datePublished":"2015-10-02T00:06:11+00:00","dateModified":"2015-11-30T20:04:11+00:00","breadcrumb":{"@id":"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/54.148.48.30\/es\/normas-reglamentos-top-of-mex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inmexico.com\/"},{"@type":"ListItem","position":2,"name":"Normas &#038; Reglamentos \u2013 Top of Mex"}]},{"@type":"WebSite","@id":"https:\/\/www.inmexico.com\/#website","url":"https:\/\/www.inmexico.com\/","name":"InMexico","description":"Luxury Without Limits","publisher":{"@id":"https:\/\/www.inmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.inmexico.com\/#organization","name":"InMexico","alternateName":"InMexico","url":"https:\/\/www.inmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","contentUrl":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","width":678,"height":208,"caption":"InMexico"},"image":{"@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/inmexicocom","https:\/\/x.com\/inmexicocom","https:\/\/www.instagram.com\/in.mexico\/"]}]}},"_links":{"self":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/pages\/4302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/comments?post=4302"}],"version-history":[{"count":4,"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/pages\/4302\/revisions"}],"predecessor-version":[{"id":5990,"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/pages\/4302\/revisions\/5990"}],"wp:attachment":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/media?parent=4302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}