{"id":56405,"date":"2026-03-02T07:47:41","date_gmt":"2026-03-02T14:47:41","guid":{"rendered":"http:\/\/www.inmexico.com\/wp-content\/uploads\/2026\/03\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg"},"modified":"2026-06-16T14:16:23","modified_gmt":"2026-06-16T21:16:23","slug":"3-claudinanico-wellness-director-of-papaya-playa-in-tulum-2","status":"inherit","type":"attachment","link":"http:\/\/54.148.48.30\/es\/3-claudinanico-wellness-director-of-papaya-playa-in-tulum-2\/","title":{"rendered":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-"},"author":13231,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"class_list":["post-56405","attachment","type-attachment","status-inherit","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3-claudinanico-wellness-director-of-papaya-playa-in-Tulum- InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum- InMexico\" \/>\n<meta property=\"og:url\" content=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-16T21:16:23+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"882\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg\",\"url\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg\",\"name\":\"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum- InMexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/#website\"},\"datePublished\":\"2026-03-02T14:47:41+00:00\",\"dateModified\":\"2026-06-16T21:16:23+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inmexico.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inmexico.com\/#website\",\"url\":\"https:\/\/www.inmexico.com\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"publisher\":{\"@id\":\"https:\/\/www.inmexico.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inmexico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.inmexico.com\/#organization\",\"name\":\"InMexico\",\"alternateName\":\"InMexico\",\"url\":\"https:\/\/www.inmexico.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"contentUrl\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"width\":678,\"height\":208,\"caption\":\"InMexico\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/inmexicocom\",\"https:\/\/x.com\/inmexicocom\",\"https:\/\/www.instagram.com\/in.mexico\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum- InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","og_locale":"es_MX","og_type":"article","og_title":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum- InMexico","og_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","article_modified_time":"2026-06-16T21:16:23+00:00","og_image":[{"width":882,"height":1600,"url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@inmexicocom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","name":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum- InMexico","isPartOf":{"@id":"https:\/\/www.inmexico.com\/#website"},"datePublished":"2026-03-02T14:47:41+00:00","dateModified":"2026-06-16T21:16:23+00:00","breadcrumb":{"@id":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inmexico.com\/"},{"@type":"ListItem","position":2,"name":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-"}]},{"@type":"WebSite","@id":"https:\/\/www.inmexico.com\/#website","url":"https:\/\/www.inmexico.com\/","name":"InMexico","description":"Luxury Without Limits","publisher":{"@id":"https:\/\/www.inmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.inmexico.com\/#organization","name":"InMexico","alternateName":"InMexico","url":"https:\/\/www.inmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","contentUrl":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","width":678,"height":208,"caption":"InMexico"},"image":{"@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/inmexicocom","https:\/\/x.com\/inmexicocom","https:\/\/www.instagram.com\/in.mexico\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"165\" height=\"300\" src=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--165x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"Claudina Nico freediving\" srcset=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--165x300.jpeg 165w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--564x1024.jpeg 564w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--768x1393.jpeg 768w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--847x1536.jpeg 847w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--100x181.jpeg 100w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--864x1567.jpeg 864w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg 882w\" sizes=\"auto, (max-width: 165px) 100vw, 165px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Claudina Nico freediving","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":882,"height":1600,"file":"2026\/03\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","filesize":84295,"sizes":{"medium":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--165x300.jpeg","width":165,"height":300,"filesize":5613,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--165x300.jpeg"},"large":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--564x1024.jpeg","width":564,"height":1024,"filesize":41685,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--564x1024.jpeg"},"thumbnail":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--150x150.jpeg","width":150,"height":150,"filesize":2982,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--150x150.jpeg"},"medium_large":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--768x1393.jpeg","width":768,"height":1393,"filesize":68595,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--768x1393.jpeg"},"1536x1536":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--847x1536.jpeg","width":847,"height":1536,"filesize":80261,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--847x1536.jpeg"},"post-thumbnail":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--100x181.jpeg","width":100,"height":181,"filesize":2687,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--100x181.jpeg"},"entry":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--864x1567.jpeg","width":864,"height":1567,"filesize":82726,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--864x1567.jpeg"},"entry-cropped":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--864x483.jpeg","width":864,"height":483,"filesize":25934,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--864x483.jpeg"},"entry-cropped-fullwidth":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--882x671.jpeg","width":882,"height":671,"filesize":38192,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum--882x671.jpeg"},"full":{"file":"3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","width":882,"height":1600,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/03\/02074743\/3-claudinanico-wellness-director-of-papaya-playa-in-Tulum-.jpeg","_links":{"self":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/media\/56405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/users\/13231"}]}}