{"id":55576,"date":"2025-09-29T17:25:23","date_gmt":"2025-09-30T00:25:23","guid":{"rendered":"http:\/\/www.inmexico.com\/wp-content\/uploads\/2025\/09\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg"},"modified":"2025-09-29T17:25:23","modified_gmt":"2025-09-30T00:25:23","slug":"3-casa-nah-tun-bedroom-deelum-conecpts-home-developer-tulum-2","status":"inherit","type":"attachment","link":"http:\/\/54.148.48.30\/es\/3-casa-nah-tun-bedroom-deelum-conecpts-home-developer-tulum-2\/","title":{"rendered":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum"},"author":13231,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"class_list":["post-55576","attachment","type-attachment","status-inherit","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum - InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum - InMexico\" \/>\n<meta property=\"og:url\" content=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"og:image\" content=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1068\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg\",\"url\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg\",\"name\":\"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum - InMexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/#website\"},\"datePublished\":\"2025-09-30T00:25:23+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inmexico.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inmexico.com\/#website\",\"url\":\"https:\/\/www.inmexico.com\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"publisher\":{\"@id\":\"https:\/\/www.inmexico.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inmexico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.inmexico.com\/#organization\",\"name\":\"InMexico\",\"alternateName\":\"InMexico\",\"url\":\"https:\/\/www.inmexico.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"contentUrl\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"width\":678,\"height\":208,\"caption\":\"InMexico\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/inmexicocom\",\"https:\/\/x.com\/inmexicocom\",\"https:\/\/www.instagram.com\/in.mexico\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum - InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","og_locale":"es_MX","og_type":"article","og_title":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum - InMexico","og_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","og_image":[{"width":1600,"height":1068,"url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@inmexicocom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","name":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum - InMexico","isPartOf":{"@id":"https:\/\/www.inmexico.com\/#website"},"datePublished":"2025-09-30T00:25:23+00:00","breadcrumb":{"@id":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inmexico.com\/"},{"@type":"ListItem","position":2,"name":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum"}]},{"@type":"WebSite","@id":"https:\/\/www.inmexico.com\/#website","url":"https:\/\/www.inmexico.com\/","name":"InMexico","description":"Luxury Without Limits","publisher":{"@id":"https:\/\/www.inmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.inmexico.com\/#organization","name":"InMexico","alternateName":"InMexico","url":"https:\/\/www.inmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","contentUrl":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","width":678,"height":208,"caption":"InMexico"},"image":{"@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/inmexicocom","https:\/\/x.com\/inmexicocom","https:\/\/www.instagram.com\/in.mexico\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-300x200.jpg 300w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1024x684.jpg 1024w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-768x513.jpg 768w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1536x1025.jpg 1536w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-100x67.jpg 100w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-864x577.jpg 864w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1200x801.jpg 1200w, http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1068,"file":"2025\/09\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","filesize":265972,"sizes":{"medium":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-300x200.jpg","width":300,"height":200,"filesize":36862,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-300x200.jpg"},"large":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1024x684.jpg","width":1024,"height":684,"filesize":124642,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1024x684.jpg"},"thumbnail":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-150x150.jpg","width":150,"height":150,"filesize":30172,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-150x150.jpg"},"medium_large":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-768x513.jpg","width":768,"height":513,"filesize":84904,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-768x513.jpg"},"1536x1536":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1536x1025.jpg","width":1536,"height":1025,"filesize":232022,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1536x1025.jpg"},"post-thumbnail":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-100x67.jpg","width":100,"height":67,"filesize":27268,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-100x67.jpg"},"entry":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-864x577.jpg","width":864,"height":577,"filesize":98221,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-864x577.jpg"},"entry-cropped":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-864x483.jpg","width":864,"height":483,"filesize":88701,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-864x483.jpg"},"entry-fullwidth":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1200x801.jpg","width":1200,"height":801,"filesize":156504,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1200x801.jpg"},"entry-cropped-fullwidth":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1200x671.jpg","width":1200,"height":671,"filesize":137831,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum-1200x671.jpg"},"full":{"file":"3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","width":1600,"height":1068,"mime_type":"image\/jpeg","source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"http:\/\/images.inmexico.com\/wp-content\/uploads\/2025\/09\/29172527\/3-Casa-Nah-Tun-Bedroom-Deelum-Conecpts-Home-Developer-Tulum.jpg","_links":{"self":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/media\/55576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/users\/13231"}]}}