{"id":45397,"date":"2020-08-27T15:36:41","date_gmt":"2020-08-27T22:36:41","guid":{"rendered":"https:\/\/www.inmexico.com\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg"},"modified":"2020-08-27T15:36:41","modified_gmt":"2020-08-27T22:36:41","slug":"w-punta-de-mita-mesa1_privatedining-png_-2","status":"inherit","type":"attachment","link":"http:\/\/54.148.48.30\/es\/w-punta-de-mita-mesa1_privatedining-png_-2\/","title":{"rendered":"W-Punta-de-Mita-Mesa1_privatedining.PNG_"},"author":13171,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false},"class_list":["post-45397","attachment","type-attachment","status-inherit","hentry","no-post-thumbnail"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>W-Punta-de-Mita-Mesa1_privatedining.PNG_ - InMexico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W-Punta-de-Mita-Mesa1_privatedining.PNG_ - InMexico\" \/>\n<meta property=\"og:url\" content=\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg\" \/>\n<meta property=\"og:site_name\" content=\"InMexico\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/inmexicocom\" \/>\n<meta property=\"og:image\" content=\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"509\" \/>\n\t<meta property=\"og:image:height\" content=\"344\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@inmexicocom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg\",\"url\":\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg\",\"name\":\"W-Punta-de-Mita-Mesa1_privatedining.PNG_ - InMexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.inmexico.com\/#website\"},\"datePublished\":\"2020-08-27T22:36:41+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg#breadcrumb\"},\"inLanguage\":\"es-MX\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.inmexico.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"W-Punta-de-Mita-Mesa1_privatedining.PNG_\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.inmexico.com\/#website\",\"url\":\"https:\/\/www.inmexico.com\/\",\"name\":\"InMexico\",\"description\":\"Luxury Without Limits\",\"publisher\":{\"@id\":\"https:\/\/www.inmexico.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.inmexico.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-MX\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.inmexico.com\/#organization\",\"name\":\"InMexico\",\"alternateName\":\"InMexico\",\"url\":\"https:\/\/www.inmexico.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-MX\",\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"contentUrl\":\"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png\",\"width\":678,\"height\":208,\"caption\":\"InMexico\"},\"image\":{\"@id\":\"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"http:\/\/www.facebook.com\/inmexicocom\",\"https:\/\/x.com\/inmexicocom\",\"https:\/\/www.instagram.com\/in.mexico\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W-Punta-de-Mita-Mesa1_privatedining.PNG_ - InMexico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","og_locale":"es_MX","og_type":"article","og_title":"W-Punta-de-Mita-Mesa1_privatedining.PNG_ - InMexico","og_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","og_site_name":"InMexico","article_publisher":"http:\/\/www.facebook.com\/inmexicocom","og_image":[{"width":509,"height":344,"url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@inmexicocom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","name":"W-Punta-de-Mita-Mesa1_privatedining.PNG_ - InMexico","isPartOf":{"@id":"https:\/\/www.inmexico.com\/#website"},"datePublished":"2020-08-27T22:36:41+00:00","breadcrumb":{"@id":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg#breadcrumb"},"inLanguage":"es-MX","potentialAction":[{"@type":"ReadAction","target":["http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inmexico.com\/"},{"@type":"ListItem","position":2,"name":"W-Punta-de-Mita-Mesa1_privatedining.PNG_"}]},{"@type":"WebSite","@id":"https:\/\/www.inmexico.com\/#website","url":"https:\/\/www.inmexico.com\/","name":"InMexico","description":"Luxury Without Limits","publisher":{"@id":"https:\/\/www.inmexico.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inmexico.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-MX"},{"@type":"Organization","@id":"https:\/\/www.inmexico.com\/#organization","name":"InMexico","alternateName":"InMexico","url":"https:\/\/www.inmexico.com\/","logo":{"@type":"ImageObject","inLanguage":"es-MX","@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/","url":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","contentUrl":"https:\/\/images.inmexico.com\/wp-content\/uploads\/2026\/09\/02102440\/InMexico-Logo-black.png","width":678,"height":208,"caption":"InMexico"},"image":{"@id":"https:\/\/www.inmexico.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/inmexicocom","https:\/\/x.com\/inmexicocom","https:\/\/www.instagram.com\/in.mexico\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/images.inmexico.com\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"203\" src=\"http:\/\/images.inmexico.com\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-300x203.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"http:\/\/images.inmexico.com\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-300x203.jpg 300w, http:\/\/images.inmexico.com\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-100x68.jpg 100w, http:\/\/images.inmexico.com\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-450x304.jpg 450w, http:\/\/images.inmexico.com\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg 509w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":509,"height":344,"file":"2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","sizes":{"medium":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-300x203.jpg","width":300,"height":203,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-300x203.jpg"},"thumbnail":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-150x150.jpg"},"us_screen":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-450x344.jpg","width":450,"height":344,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-450x344.jpg"},"post-thumbnail":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-100x68.jpg","width":100,"height":68,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-100x68.jpg"},"rpwe-thumbnail":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-45x45.jpg","width":45,"height":45,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-45x45.jpg"},"woocommerce_thumbnail":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-258x275.jpg","width":258,"height":275,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-258x275.jpg"},"woocommerce_single":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-450x304.jpg","width":450,"height":304,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-450x304.jpg"},"woocommerce_gallery_thumbnail":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-100x100.jpg"},"shop_catalog":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-258x275.jpg","width":258,"height":275,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-258x275.jpg"},"shop_single":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-450x304.jpg","width":450,"height":304,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-450x304.jpg"},"shop_thumbnail":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_-100x100.jpg"},"full":{"file":"W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","width":509,"height":344,"mime_type":"image\/jpeg","source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"http:\/\/54.148.48.30\/wp-content\/uploads\/2020\/08\/W-Punta-de-Mita-Mesa1_privatedining.PNG_.jpg","_links":{"self":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/media\/45397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/54.148.48.30\/es\/wp-json\/wp\/v2\/users\/13171"}]}}